{"id":7955,"date":"2020-01-20T09:00:21","date_gmt":"2020-01-20T12:00:21","guid":{"rendered":"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/"},"modified":"2020-01-20T09:00:21","modified_gmt":"2020-01-20T12:00:21","slug":"6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar","status":"publish","type":"post","link":"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/","title":{"rendered":"6 indicadores de vendas que voc\u00ea n\u00e3o pode deixar de analisar"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]A \u00e1rea comercial \u00e9 fundamental para o desenvolvimento e a evolu\u00e7\u00e3o de uma empresa. Assim, precisa estar muito bem organizada e dentro de um bom planejamento de neg\u00f3cio. Al\u00e9m disso, \u00e9 importante que seus resultados e desempenho sejam acompanhados de perto. Para realizar esse trabalho de mensura\u00e7\u00e3o, existem os indicadores de vendas.<\/p>\n<p>Eles s\u00e3o instrumentos respons\u00e1veis pela defini\u00e7\u00e3o dos objetivos qualitativos da empresa e de todos os colaboradores. \u00c9 essencial acompanh\u00e1-los, pois eles ajudam na gest\u00e3o de desempenho e na previs\u00e3o de resultados.<\/p>\n<p>Neste post, vamos mostrar 6 indicadores de vendas que voc\u00ea n\u00e3o pode deixar de analisar. Confira!<\/p>\n<h2>1. N\u00famero de leads gerados<\/h2>\n<p>Os leads podem ser definidos como as pessoas que demonstraram interesse em um conte\u00fado da sua empresa e que, para terem acesso a ele, preencheram alguns dados de identifica\u00e7\u00e3o.<\/p>\n<p>Ap\u00f3s um per\u00edodo de matura\u00e7\u00e3o, eles podem se transformar em oportunidades. Ent\u00e3o, mostrar\u00e3o interesse de alguma maneira pela solu\u00e7\u00e3o apresentada pelo seu neg\u00f3cio. Nesse caso, seu principal objetivo \u00e9 executar uma estrat\u00e9gia para que esse p\u00fablico seja captado e convertido em <a href=\"https:\/\/ddwb.com.br\/blog\/tudo-que-voce-precisa-saber-sobre-a-jornada-do-consumidor-digital\/\">consumidores<\/a> da sua empresa.<\/p>\n<p>Por\u00e9m, para que a \u00e1rea comercial tenha mais controle sobre suas a\u00e7\u00f5es e informa\u00e7\u00f5es, \u00e9 fundamental ter um indicador que consiga mencionar o n\u00famero de leads gerados. Por meio desse controle, \u00e9 poss\u00edvel saber se as <a href=\"https:\/\/ddwb.com.br\/blog\/campanha-de-midia-de-performance-tudo-o-que-voce-precisa-conhecer\/\">campanhas<\/a> de marketing executadas no topo, meio e fundo do funil est\u00e3o realmente sendo efetivas e gerando resultados positivos.<\/p>\n<p>O controle desse indicador \u00e9 feito ao buscar informa\u00e7\u00f5es dos potenciais <a href=\"https:\/\/ddwb.com.br\/blog\/entenda-o-que-e-storytelling-e-como-usa-lo-para-encantar-clientes\/\">clientes<\/a>, seja por meio de conte\u00fados baixados, cadastro em newsletter, inscri\u00e7\u00e3o em eventos, entre outros. Com esses dados, vai ser poss\u00edvel saber o n\u00famero de leads gerados em um per\u00edodo espec\u00edfico e criar estrat\u00e9gias cada vez mais personalizadas para esse p\u00fablico.<\/p>\n<h2>2. Ticket m\u00e9dio<\/h2>\n<p>Saber qual o ticket m\u00e9dio de uma empresa \u00e9 essencial para o planejamento de novas estrat\u00e9gias comerciais e de <a href=\"https:\/\/ddwb.com.br\/blog\/entenda-a-importancia-do-marketing-de-atracao-para-as-empresas\/\">marketing<\/a>. Esse indicador possibilita que o gestor fique ciente sobre o comportamento de seus consumidores com a marca. Em resumo, o ticket m\u00e9dio mostra o gasto m\u00e9dio por pedido.<\/p>\n<p>Quando falamos em indicadores de venda, ele \u00e9 um dos mais importantes. Ou seja, est\u00e1 ligado de maneira direta ao faturamento do neg\u00f3cio. Algumas a\u00e7\u00f5es podem ser feitas para aumentar o ticket m\u00e9dio, como oferecer frete gr\u00e1tis em compras acima de determinado valor, promover descontos progressivos, criar combos de servi\u00e7os e produtos, entre outros.<\/p>\n<h2>3. Volume de vendas<\/h2>\n<p>Fazer uma mensura\u00e7\u00e3o dos resultados em todos os setores e realizar um acompanhamento, principalmente, da \u00e1rea comercial, s\u00e3o fundamentais\u00a0para o desenvolvimento de um neg\u00f3cio. \u00c9 preciso investir e utilizar plataformas para acompanhar de perto o <a href=\"https:\/\/ddwb.com.br\/blog\/entenda-como-alavancar-as-vendas-da-sua-loja-virtual\/\">volume de vendas<\/a>, com o objetivo de ter em m\u00e3os dados suficientes para planejar e executar novas estrat\u00e9gias.<\/p>\n<p>Esse indicador de vendas \u00e9 essencial para que a gest\u00e3o de um neg\u00f3cio seja cada vez mais organizada. Com esses dados e informa\u00e7\u00f5es, a empresa consegue identificar as causas e os efeitos espec\u00edficos de algumas estrat\u00e9gias executadas. Al\u00e9m disso, \u00e9 poss\u00edvel fazer previs\u00f5es sobre os faturamentos dos meses seguintes.<\/p>\n<h2>4. CAC<\/h2>\n<p>O custo de aquisi\u00e7\u00e3o por cliente (CAC) \u00e9 outro indicador muito importante para que a empresa possa se organizar e criar novas estrat\u00e9gias de desenvolvimento. Ele \u00e9 respons\u00e1vel por\u00a0todo o acompanhamento dos gastos e investimentos feitos pelos consumidores at\u00e9 eles se tornarem clientes do seu neg\u00f3cio.<\/p>\n<p>Para que os dados disponibilizados por esse indicador sejam considerados, \u00e9 preciso que a empresa levante todo o investimento que foi realizado, desde as a\u00e7\u00f5es de marketing, time comercial, CRM, at\u00e9 os gastos nas transa\u00e7\u00f5es.<\/p>\n<p>Ap\u00f3s pegar essas informa\u00e7\u00f5es e somar tudo o que foi investido para adquirir um cliente, divida o valor desse investimento pelo n\u00famero total de clientes em um determinado per\u00edodo ser\u00e1 poss\u00edvel identificar o CAC.<\/p>\n<p>Esse indicador\u00a0\u00e9 respons\u00e1vel por disponibilizar informa\u00e7\u00f5es para as empresas de maneira que elas consigam avaliar se est\u00e1 valendo a pena ou n\u00e3o alguma determinada estrat\u00e9gia para captar novos clientes. Caso o custo de aquisi\u00e7\u00e3o por cliente seja maior do que o gasto m\u00e9dio, significa que o\u00a0neg\u00f3cio est\u00e1 tendo um certo preju\u00edzo e \u00e9 preciso repensar suas a\u00e7\u00f5es.<\/p>\n<p>Outro indicador muito importante \u00e9 o LTV (Lifetime Value), que pode ser definido como todo o valor que\u00a0o cliente\u00a0deixa na sua empresa enquanto ele est\u00e1 ligado ao seu neg\u00f3cio ou &#8220;valor do tempo de vida do cliente&#8221;.<\/p>\n<p>Caso o valor dessa opera\u00e7\u00e3o seja\u00a0menor do que o LTV, significa que o resultado n\u00e3o \u00e9 positivo, e o neg\u00f3cio est\u00e1\u00a0gastando mais para captar um novo cliente do que o retorno desse consumidor para a receita da empresa.<\/p>\n<h2>5. Ciclo m\u00e9dio de compra<\/h2>\n<p>Voc\u00ea sabe como calcular o intervalo de tempo que um consumidor demora para realizar uma nova compra no seu neg\u00f3cio? Essa \u00e9 uma informa\u00e7\u00e3o que pode ser muito \u00fatil para os setores comercial, de marketing e de comunica\u00e7\u00e3o criarem as melhores estrat\u00e9gias de venda. Esses dados podem ser disponibilizados por meio de uma avalia\u00e7\u00e3o do <a href=\"https:\/\/ddwb.com.br\/blog\/o-que-e-ciclo-de-vendas-e-como-encurta-lo\/\">ciclo<\/a> m\u00e9dio de compra.<\/p>\n<p>Esse indicador \u00e9 respons\u00e1vel por identificar se h\u00e1 algum padr\u00e3o de compra em diversos segmentos e\u00a0se os usu\u00e1rios est\u00e3o acessando o <a href=\"https:\/\/ddwb.com.br\/blog\/aqui-esta-o-guia-completo-sobre-como-gerar-trafego-para-site\/\">site<\/a> de forma peri\u00f3dica, entre outras a\u00e7\u00f5es. Al\u00e9m disso, calcular o ciclo m\u00e9dio de compra \u00e9 importante para fazer uma classifica\u00e7\u00e3o dos consumidores. Assim, para os que est\u00e3o inativos, \u00e9 poss\u00edvel executar uma nova estrat\u00e9gia personalizada para esse p\u00fablico.<\/p>\n<p>Esses dados s\u00e3o essenciais para fazer uma identifica\u00e7\u00e3o da frequ\u00eancia de visita dos vendedores. Relacionar as informa\u00e7\u00f5es com o ticket m\u00e9dio do cliente para identificar se as a\u00e7\u00f5es est\u00e3o sendo positivas, realizar uma otimiza\u00e7\u00e3o da agenda dos representantes e projetar <a href=\"https:\/\/ddwb.com.br\/blog\/o-que-e-ciclo-de-vendas-e-como-encurta-lo\/\">vendas<\/a> mais realistas.<\/p>\n<h2>6. Taxa de convers\u00e3o<\/h2>\n<p>A taxa de convers\u00e3o \u00e9 um dos indicadores de vendas mais importantes dentro de uma empresa. Ela \u00e9 respons\u00e1vel por fazer a avalia\u00e7\u00e3o da efici\u00eancia de todos os colaboradores do setor comercial. Geralmente, isso \u00e9 feito ao relacionar o n\u00famero de oportunidades criadas \u00e0s que realmente se converteram em vendas.<\/p>\n<p>Marketing e vendas s\u00e3o setores distintos, mas caminham juntos. Um neg\u00f3cio pode fazer uso do <a href=\"https:\/\/rockcontent.com\/blog\/testes-ab\/\">testes A\/B<\/a>,\u00a0respons\u00e1vel por comparar as vari\u00e1veis de marketing. Com essas informa\u00e7\u00f5es, \u00e9 poss\u00edvel determinar qual\u00a0estrat\u00e9gia gera a maior taxa de convers\u00e3o. Por meio desses n\u00fameros, a equipe comercial consegue identificar as melhores a\u00e7\u00f5es.<\/p>\n<p>Identificar em que etapa do funil de vendas sua persona est\u00e1 presente \u00e9 fundamental para que a empresa fa\u00e7a um bom <a href=\"https:\/\/ddwb.com.br\/blog\/aprenda-a-fazer-um-planejamento-de-marketing-digital-em-8-passos\/\">planejamento<\/a> e execute as estrat\u00e9gias de maneira correta. Os indicadores de vendas s\u00e3o muito importantes para realizar o acompanhamento e fazer a mensura\u00e7\u00e3o dos resultados de todas as \u00e1reas da empresa. Saber o n\u00famero de leads gerados, o ciclo m\u00e9dio de compra e o ticket m\u00e9dio, por exemplo, pode auxiliar no desenvolvimento do neg\u00f3cio.<\/p>\n<p>E a\u00ed, conseguiu entender melhor sobre os indicadores de vendas que voc\u00ea n\u00e3o pode deixar de analisar? Aguardamos seu coment\u00e1rio no post com sua opini\u00e3o sobre o assunto e outros indicadores importantes.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]A \u00e1rea comercial \u00e9 fundamental para o desenvolvimento e a evolu\u00e7\u00e3o de uma empresa. Assim, precisa estar muito bem organizada e dentro de um bom planejamento de neg\u00f3cio. Al\u00e9m disso, \u00e9 importante que seus resultados e desempenho sejam acompanhados de perto. Para realizar esse trabalho de mensura\u00e7\u00e3o, existem os indicadores de vendas. Eles s\u00e3o instrumentos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7956,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[158],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>6 indicadores de vendas que voc\u00ea n\u00e3o pode deixar de analisar - Blog de Marketing Digital, Inbound e Performance | DDWB Ag\u00eancia<\/title>\n<meta name=\"description\" content=\"Alguns indicadores s\u00e3o muito importantes para an\u00e1lises e mensura\u00e7\u00e3o de vendas. Saiba quais deles voc\u00ea deve investir no seu neg\u00f3cio!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"6 indicadores de vendas que voc\u00ea n\u00e3o pode deixar de analisar - Blog de Marketing Digital, Inbound e Performance | DDWB Ag\u00eancia\" \/>\n<meta property=\"og:description\" content=\"Alguns indicadores s\u00e3o muito importantes para an\u00e1lises e mensura\u00e7\u00e3o de vendas. Saiba quais deles voc\u00ea deve investir no seu neg\u00f3cio!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Marketing Digital, Inbound e Performance | DDWB Ag\u00eancia\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-20T12:00:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ddwb.com.br\/blog\/wp-content\/uploads\/2020\/01\/306666-6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2119\" \/>\n\t<meta property=\"og:image:height\" content=\"1415\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcelo Rama\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcelo Rama\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/\",\"url\":\"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/\",\"name\":\"6 indicadores de vendas que voc\u00ea n\u00e3o pode deixar de analisar - Blog de Marketing Digital, Inbound e Performance | DDWB Ag\u00eancia\",\"isPartOf\":{\"@id\":\"https:\/\/ddwb.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ddwb.com.br\/blog\/wp-content\/uploads\/2020\/01\/306666-6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar.jpg\",\"datePublished\":\"2020-01-20T12:00:21+00:00\",\"dateModified\":\"2020-01-20T12:00:21+00:00\",\"author\":{\"@id\":\"https:\/\/ddwb.com.br\/blog\/#\/schema\/person\/14e03d61c9c627477b5251a9ebd97ee0\"},\"description\":\"Alguns indicadores s\u00e3o muito importantes para an\u00e1lises e mensura\u00e7\u00e3o de vendas. Saiba quais deles voc\u00ea deve investir no seu neg\u00f3cio!\",\"breadcrumb\":{\"@id\":\"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/#primaryimage\",\"url\":\"https:\/\/ddwb.com.br\/blog\/wp-content\/uploads\/2020\/01\/306666-6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar.jpg\",\"contentUrl\":\"https:\/\/ddwb.com.br\/blog\/wp-content\/uploads\/2020\/01\/306666-6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar.jpg\",\"width\":2119,\"height\":1415,\"caption\":\"vendas-ddwb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ddwb.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"6 indicadores de vendas que voc\u00ea n\u00e3o pode deixar de analisar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ddwb.com.br\/blog\/#website\",\"url\":\"https:\/\/ddwb.com.br\/blog\/\",\"name\":\"Blog de Marketing Digital, Inbound e Performance | DDWB Ag\u00eancia\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ddwb.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ddwb.com.br\/blog\/#\/schema\/person\/14e03d61c9c627477b5251a9ebd97ee0\",\"name\":\"Marcelo Rama\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ddwb.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g\",\"caption\":\"Marcelo Rama\"},\"url\":\"https:\/\/ddwb.com.br\/blog\/author\/marcelo-rama\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"6 indicadores de vendas que voc\u00ea n\u00e3o pode deixar de analisar - Blog de Marketing Digital, Inbound e Performance | DDWB Ag\u00eancia","description":"Alguns indicadores s\u00e3o muito importantes para an\u00e1lises e mensura\u00e7\u00e3o de vendas. Saiba quais deles voc\u00ea deve investir no seu neg\u00f3cio!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/","og_locale":"pt_BR","og_type":"article","og_title":"6 indicadores de vendas que voc\u00ea n\u00e3o pode deixar de analisar - Blog de Marketing Digital, Inbound e Performance | DDWB Ag\u00eancia","og_description":"Alguns indicadores s\u00e3o muito importantes para an\u00e1lises e mensura\u00e7\u00e3o de vendas. Saiba quais deles voc\u00ea deve investir no seu neg\u00f3cio!","og_url":"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/","og_site_name":"Blog de Marketing Digital, Inbound e Performance | DDWB Ag\u00eancia","article_published_time":"2020-01-20T12:00:21+00:00","og_image":[{"width":2119,"height":1415,"url":"https:\/\/ddwb.com.br\/blog\/wp-content\/uploads\/2020\/01\/306666-6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar.jpg","type":"image\/jpeg"}],"author":"Marcelo Rama","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marcelo Rama","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/","url":"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/","name":"6 indicadores de vendas que voc\u00ea n\u00e3o pode deixar de analisar - Blog de Marketing Digital, Inbound e Performance | DDWB Ag\u00eancia","isPartOf":{"@id":"https:\/\/ddwb.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/#primaryimage"},"image":{"@id":"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/#primaryimage"},"thumbnailUrl":"https:\/\/ddwb.com.br\/blog\/wp-content\/uploads\/2020\/01\/306666-6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar.jpg","datePublished":"2020-01-20T12:00:21+00:00","dateModified":"2020-01-20T12:00:21+00:00","author":{"@id":"https:\/\/ddwb.com.br\/blog\/#\/schema\/person\/14e03d61c9c627477b5251a9ebd97ee0"},"description":"Alguns indicadores s\u00e3o muito importantes para an\u00e1lises e mensura\u00e7\u00e3o de vendas. Saiba quais deles voc\u00ea deve investir no seu neg\u00f3cio!","breadcrumb":{"@id":"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/#primaryimage","url":"https:\/\/ddwb.com.br\/blog\/wp-content\/uploads\/2020\/01\/306666-6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar.jpg","contentUrl":"https:\/\/ddwb.com.br\/blog\/wp-content\/uploads\/2020\/01\/306666-6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar.jpg","width":2119,"height":1415,"caption":"vendas-ddwb"},{"@type":"BreadcrumbList","@id":"https:\/\/ddwb.com.br\/blog\/6-indicadores-de-vendas-que-voce-nao-pode-deixar-de-analisar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ddwb.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"6 indicadores de vendas que voc\u00ea n\u00e3o pode deixar de analisar"}]},{"@type":"WebSite","@id":"https:\/\/ddwb.com.br\/blog\/#website","url":"https:\/\/ddwb.com.br\/blog\/","name":"Blog de Marketing Digital, Inbound e Performance | DDWB Ag\u00eancia","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ddwb.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/ddwb.com.br\/blog\/#\/schema\/person\/14e03d61c9c627477b5251a9ebd97ee0","name":"Marcelo Rama","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ddwb.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"Marcelo Rama"},"url":"https:\/\/ddwb.com.br\/blog\/author\/marcelo-rama\/"}]}},"_links":{"self":[{"href":"https:\/\/ddwb.com.br\/blog\/wp-json\/wp\/v2\/posts\/7955"}],"collection":[{"href":"https:\/\/ddwb.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddwb.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddwb.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ddwb.com.br\/blog\/wp-json\/wp\/v2\/comments?post=7955"}],"version-history":[{"count":0,"href":"https:\/\/ddwb.com.br\/blog\/wp-json\/wp\/v2\/posts\/7955\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddwb.com.br\/blog\/wp-json\/wp\/v2\/media\/7956"}],"wp:attachment":[{"href":"https:\/\/ddwb.com.br\/blog\/wp-json\/wp\/v2\/media?parent=7955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddwb.com.br\/blog\/wp-json\/wp\/v2\/categories?post=7955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddwb.com.br\/blog\/wp-json\/wp\/v2\/tags?post=7955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}